{"id":138050,"date":"2025-06-12T12:43:10","date_gmt":"2025-06-12T10:43:10","guid":{"rendered":"https:\/\/diaridigital.urv.cat\/?p=138050"},"modified":"2025-06-12T12:43:10","modified_gmt":"2025-06-12T10:43:10","slug":"u-ranking-25","status":"publish","type":"post","link":"https:\/\/diaridigital.urv.cat\/es\/u-ranking-25\/","title":{"rendered":"La URV es la tercera universidad del Estado en Artes y Humanidades"},"content":{"rendered":"<p>La edici\u00f3n de este a\u00f1o del U-Ranking, impulsado por la Fundaci\u00f3n BBVA, destaca el rendimiento de la URV en Artes y Humanidades, situ\u00e1ndola como la tercera universidad del Estado \u2014y de Catalunya\u2014 en este \u00e1mbito. El an\u00e1lisis que han llevado a cabo, junto con el Instituto Valenciano de Investigaciones Econ\u00f3micas, reconoce a la Universidad como la novena del estado en la clasificaci\u00f3n general \u2014con una puntuaci\u00f3n de 88 puntos de 100 posibles\u2014 que lidera la Universidad Pompeu Fabra. Teniendo en cuenta exclusivamente las universidades catalanas, la URV se sit\u00faa en quinta posici\u00f3n, s\u00f3lo superada por la Aut\u00f2noma de Barcelona, la Polit\u00e8cnica de Catalunya, la Universitat de Barcelona y, la propia UPF.<\/p>\n<h5>Una universidad destacada en investigaci\u00f3n<\/h5>\n<p>El informe de la Fundaci\u00f3n BBVA ha analizado par\u00e1metros de 72 universidades espa\u00f1olas, 48 p\u00fablicas y 24 privadas. El ranking ordena a las universidades en funci\u00f3n de su rendimiento, teniendo en cuenta una serie de indicadores en los \u00e1mbitos de docencia, investigaci\u00f3n e innovaci\u00f3n, e inserci\u00f3n laboral.<\/p>\n<p>En este sentido, los datos reflejan el buen papel de la URV en investigaci\u00f3n e innovaci\u00f3n, ranking en el que ocupa la quinta posici\u00f3n en el Estado \u2014y en Catalunya\u2014 con una puntuaci\u00f3n de 83 puntos sobre 100.<\/p>\n<p>El U-Ranking tambi\u00e9n clasifica los resultados en las cinco ramas de ense\u00f1anza: artes y humanidades, ciencias sociales y jur\u00eddicas, ciencias, ingenier\u00eda y arquitectura, y ciencias de la salud, como se puede comprobar en la <a href=\"https:\/\/www.u-ranking.es\/ranking\">p\u00e1gina web del proyecto<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As\u00ed lo indica la nueva edici\u00f3n del U-Ranking, que sit\u00faa a la universidad tarraconense como la novena del Estado y la quinta catalana a nivel global<\/p>\n","protected":false},"author":139,"featured_media":122960,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[83,94,93,123],"tags":[4879],"class_list":["post-138050","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general-es","category-institucion","category-la-urv","category-notas-prensa","tag-ranquings-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/diaridigital.urv.cat\/es\/wp-json\/wp\/v2\/posts\/138050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diaridigital.urv.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diaridigital.urv.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diaridigital.urv.cat\/es\/wp-json\/wp\/v2\/users\/139"}],"replies":[{"embeddable":true,"href":"https:\/\/diaridigital.urv.cat\/es\/wp-json\/wp\/v2\/comments?post=138050"}],"version-history":[{"count":0,"href":"https:\/\/diaridigital.urv.cat\/es\/wp-json\/wp\/v2\/posts\/138050\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diaridigital.urv.cat\/es\/wp-json\/wp\/v2\/media\/122960"}],"wp:attachment":[{"href":"https:\/\/diaridigital.urv.cat\/es\/wp-json\/wp\/v2\/media?parent=138050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diaridigital.urv.cat\/es\/wp-json\/wp\/v2\/categories?post=138050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diaridigital.urv.cat\/es\/wp-json\/wp\/v2\/tags?post=138050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}